{"id":393,"date":"2018-07-31T17:56:56","date_gmt":"2018-07-31T15:56:56","guid":{"rendered":"http:\/\/mood36.com\/?post_type=portfolio&#038;p=393"},"modified":"2018-07-31T17:57:59","modified_gmt":"2018-07-31T15:57:59","slug":"digital-in-action","status":"publish","type":"portfolio","link":"https:\/\/mood36.com\/index.php\/portfolio-articoli\/digital-in-action\/","title":{"rendered":"DIGITAL IN ACTION"},"content":{"rendered":"<p>L\u2019evoluzione tecnologica \u00e8 fluida, cambia in continuazione e sembra non fermarsi mai.<\/p>\n<p>Non \u00e8 informe: semplicemente, acquista nuove forme.<\/p>\n<p>Forme che dobbiamo sperimentare, accogliere, sfidare perch\u00e9 il futuro deve essere sempre anticipato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019evoluzione tecnologica \u00e8 fluida, cambia in continuazione e sembra non fermarsi mai. Non \u00e8 informe: semplicemente, acquista nuove forme. Forme che dobbiamo sperimentare, accogliere, sfidare perch\u00e9 il futuro deve essere sempre anticipato.<\/p>\n","protected":false},"featured_media":375,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"portfolio_entries":[],"_links":{"self":[{"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/portfolio\/393"}],"collection":[{"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/comments?post=393"}],"version-history":[{"count":1,"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/portfolio\/393\/revisions"}],"predecessor-version":[{"id":394,"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/portfolio\/393\/revisions\/394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/media\/375"}],"wp:attachment":[{"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/media?parent=393"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/tags?post=393"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/mood36.com\/index.php\/wp-json\/wp\/v2\/portfolio_entries?post=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}